{"id":8033,"date":"2021-10-28T13:24:41","date_gmt":"2021-10-28T13:24:41","guid":{"rendered":"https:\/\/luxuryhomefloripa.com\/?p=8033"},"modified":"2023-02-24T11:59:09","modified_gmt":"2023-02-24T14:59:09","slug":"casa-cor-sp-2021","status":"publish","type":"post","link":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/","title":{"rendered":"CASACOR SP 2021"},"content":{"rendered":"<p class=\"wp-block-paragraph\">CASACOR SP 2021: El t\u00e9rmino universo casa nunca tuvo tanto sentido. Debido a un largo per\u00edodo de aislamiento, el concepto de vivir bien ha sufrido cambios importantes. Por ello, invertir en vivienda se ha convertido en una prioridad y el mercado est\u00e1 en auge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este contexto, los consumidores de dise\u00f1o y arquitectura est\u00e1n cada vez m\u00e1s atentos a las tendencias del sector. Y actualmente esperaba con ansias la reapertura de CASACOR SP (que no estuvo cerrada el a\u00f1o pasado debido al per\u00edodo de aislamiento).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2021\/08\/23-Tufi-Mousse-Salvador-Cordaro.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"918\" height=\"612\" sizes=\"(max-width: 918px) 100vw, 918px\" src=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2021\/08\/23-Tufi-Mousse-Salvador-Cordaro.jpg\" alt=\"CASACOR SP 2021\" class=\"wp-image-39209\" srcset=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/08\/23-Tufi-Mousse-Salvador-Cordaro.jpg 918w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/08\/23-Tufi-Mousse-Salvador-Cordaro-300x200.jpg 300w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/08\/23-Tufi-Mousse-Salvador-Cordaro-768x512.jpg 768w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/08\/23-Tufi-Mousse-Salvador-Cordaro-240x160.jpg 240w\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n volvi\u00f3 renovada. En un a\u00f1o marcado por cambios, el <a href=\"https:\/\/casacor.abril.com.br\/mostras\/sao-paulo\/\">CASACOR S\u00e3o Paulo<\/a> devolver <strong>ser itinerante y tiene lugar en una nueva direcci\u00f3n: <\/strong>despu\u00e9s <a href=\"https:\/\/casacor.abril.com.br\/noticias\/planeta-casa-o-que-voce-vai-encontrar-na-casacor-sao-paulo-2019\/\">larga temporada en el Jockey Club<\/a> \u2013 donde permaneci\u00f3 durante 14 a\u00f1os \u2013 la exposici\u00f3n m\u00e1s grande y reconocida en el segmento de arquitectura, decoraci\u00f3n, dise\u00f1o y paisajismo de Am\u00e9rica se lleva a cabo en el espacio de eventos multiprop\u00f3sito m\u00e1s nuevo de Am\u00e9rica Latina, anexo al Allianz Parque Arena, Parque Mirante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Casa Cor es un term\u00f3metro, especialmente la exposici\u00f3n de S\u00e3o Paulo considerada la m\u00e1s grande de Am\u00e9rica Latina.<br>Entonces, enumeremos algunas tendencias muy fuertes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2714\ufe0fL\u00edneas org\u00e1nicas. En la exposici\u00f3n se vieron pocas l\u00edneas rectas, especialmente en los sof\u00e1s;<br>\u2714\ufe0fTonos tierra. La terracota es la favorita de la temporada (rayando la exageraci\u00f3n);<br>\u2714\ufe0fMateriales naturales;<br>\u2714\ufe0fHallazgos opacos;<br>\u2714\ufe0fPlantas deshidratadas;<br>\u2714\ufe0fBiofilia, el verde ha invadido todos los ambientes de la casa;<br>\u2714\ufe0fEl estilo industrial dio paso a un estilo m\u00e1s natural y r\u00fastico con fuertes referencias a la brasilidad.<br>\u2714\ufe0fLa artesan\u00eda nacional nunca ha sido m\u00e1s valorada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-casa-original\"><strong>La casa original<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La casa original<\/strong> Promueve una serie de reflexiones, sobre todo por el evidente deseo de volver a los or\u00edgenes, de buscar en la ascendencia y la sencillez el necesario equilibrio entre el pasado y el futuro. La experiencia propuesta por CASACOR S\u00e3o Paulo comienza justo en la entrada, donde el artista invitado, <strong>Felipe Morozini<\/strong>, presenta una instalaci\u00f3n sinest\u00e9sica e inmersiva. De esta manera, invita al visitante a adentrarse en el universo de CASACOR, a trav\u00e9s de un gran t\u00fanel, en el que las viviendas de la naturaleza, como colmenas, nidos de Jo\u00e3o de Barro, termiteros, conchas de moluscos y capullos, representan el hogar ancestral, comenzando el gran recorrido que propone el evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La instalaci\u00f3n, llamada <strong>Una luz al final del t\u00fanel<\/strong>, 100% es sostenible y est\u00e1 fabricado con materiales reutilizables, ocupando toda la entrada, con grandes paneles LED, que mostrar\u00e1n proyecciones creadas por el artista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSiempre tuve el deseo de materializar el sentimiento colectivo de luz al final del t\u00fanel y unirme a CASACOR S\u00e3o Paulo me dio esta oportunidad. La idea es hablar un poco de esperanza en este momento adverso que estamos viviendo, trayendo el ejercicio de mirar atr\u00e1s, pensar en lo que ya pas\u00f3. Adem\u00e1s, quer\u00eda homenajear a los arquitectos de la naturaleza, con una visi\u00f3n que pone lo peque\u00f1o en proporciones grandiosas. Quien visite el espacio vivir\u00e1 una experiencia \u00fanica y muy personal, con las im\u00e1genes, olores y sonidos que estamos preparando\u201d, afirma Morozini.<\/p>","protected":false},"excerpt":{"rendered":"<p>CASACOR SP 2021: El t\u00e9rmino &quot;universo hogar&quot; nunca ha tenido tanto sentido. Debido al largo periodo de aislamiento, el concepto de vivir bien ha experimentado cambios importantes. Invertir en viviendas se ha convertido en una prioridad y el mercado est\u00e1 en auge. En este contexto, los consumidores de dise\u00f1o y arquitectura est\u00e1n cada vez m\u00e1s atentos a las tendencias\u2026<\/p>","protected":false},"author":10,"featured_media":39205,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_daextam_enable_autolinks":"","footnotes":""},"categories":[243],"tags":[],"class_list":["post-8033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CASACOR SP 2021<\/title>\n<meta name=\"description\" content=\"CASACOR SP 2021: O termo universo da casa nunca fez tanto sentido. Por conta de um longo per\u00edodo de isolamento, o conceito de morar bem...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CASACOR SP 2021\" \/>\n<meta property=\"og:description\" content=\"Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, Casas, Coberturas, Terrenos e Lan\u00e7amentos Imobili\u00e1rios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxury Home Floripa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/luxuryhomefloripa\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-28T13:24:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-24T14:59:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/10\/23-Tufi-Mousse-Salvador-Cordaro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"918\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Day Rocco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Day Rocco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/\"},\"author\":{\"name\":\"Day Rocco\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/person\\\/a60113ff81d1c0dd057e6ea02b4067b4\"},\"headline\":\"CASACOR SP 2021\",\"datePublished\":\"2021-10-28T13:24:41+00:00\",\"dateModified\":\"2023-02-24T14:59:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/\"},\"wordCount\":536,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/23-Tufi-Mousse-Salvador-Cordaro.jpg\",\"articleSection\":[\"Decor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/\",\"name\":\"CASACOR SP 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/23-Tufi-Mousse-Salvador-Cordaro.jpg\",\"datePublished\":\"2021-10-28T13:24:41+00:00\",\"dateModified\":\"2023-02-24T14:59:09+00:00\",\"description\":\"CASACOR SP 2021: O termo universo da casa nunca fez tanto sentido. Por conta de um longo per\u00edodo de isolamento, o conceito de morar bem...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/23-Tufi-Mousse-Salvador-Cordaro.jpg\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/23-Tufi-Mousse-Salvador-Cordaro.jpg\",\"width\":918,\"height\":612,\"caption\":\"CASACOR SP 2021\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/es\\\/casa-cor-sp-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CASACOR SP 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#website\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\",\"name\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\",\"description\":\"Imobili\u00e1ria em Jurer\u00ea com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, casas, coberturas, terrenos e lan\u00e7amentos imobili\u00e1rios\",\"publisher\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\"},\"alternateName\":\"Luxury Home Floripa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\",\"name\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\",\"alternateName\":\"Luxury Home Floripa\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"width\":1200,\"height\":675,\"caption\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\"},\"image\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/maps.app.goo.gl\\\/ymFbE67htB8wpMeU9\",\"https:\\\/\\\/www.facebook.com\\\/luxuryhomefloripa\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LuxuryHomeFloripa\",\"https:\\\/\\\/x.com\\\/luxuryhomefln\"],\"description\":\"Imobili\u00e1ria em Jurer\u00ea com im\u00f3veis \u00e0 venda na cidade de Florian\u00f3polis e em toda a regi\u00e3o da grande Florian\u00f3polis. Equipe especializada no mercado de Florian\u00f3polis com mais de 20 anos de experi\u00eancia.\",\"email\":\"dayrocco@luxuryhomefloripa.com.br\",\"telephone\":\"+5548996606799\",\"legalName\":\"LUXURY HOME FLORIPA\",\"foundingDate\":\"2021-01-23\",\"vatID\":\"57.909.495\\\/0001-93\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"R. Prof. Heinz Braunsperger, 88 - Loja 3 - Jurer\u00ea Internacional\",\"addressLocality\":\"Florian\u00f3polis\",\"addressRegion\":\"Santa Catarina\",\"postalCode\":\"88053-680\",\"addressCountry\":\"BR\"},\"priceRange\":\"$$$\",\"hasMap\":\"https:\\\/\\\/maps.app.goo.gl\\\/ymFbE67htB8wpMeU9\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":-27.4386881,\"longitude\":-48.4831842},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\",\"https:\\\/\\\/schema.org\\\/Saturday\",\"https:\\\/\\\/schema.org\\\/Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5.0\",\"reviewCount\":\"25\",\"bestRating\":\"5\",\"worstRating\":\"1\"},\"identifier\":{\"@type\":\"PropertyValue\",\"name\":\"CRECI\",\"value\":\"11161\"},\"areaServed\":{\"@type\":\"City\",\"name\":\"Florian\u00f3polis\"},\"employee\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#agent-day-rocco\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/person\\\/a60113ff81d1c0dd057e6ea02b4067b4\",\"name\":\"Day Rocco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"caption\":\"Day Rocco\"},\"description\":\"Sou especialista em im\u00f3veis de luxo, alto padr\u00e3o e investimentos imobili\u00e1rios no Sul do Brasil. Reconhecida pelo atendimento premium e bil\u00edngue, acompanho cada cliente desde a primeira busca at\u00e9 a entrega das chaves, conectando compradores e investidores aos empreendimentos mais exclusivos da ilha, de Jurer\u00ea Internacional ao Campeche, passando por Cacup\u00e9, Jo\u00e3o Paulo e Praia Brava. Fundadora da Luxury Home Floripa, acumulo mais de R$ 320 milh\u00f5es em vendas ao longo de cinco anos de atua\u00e7\u00e3o no mercado imobili\u00e1rio de alta renda. Aqui compartilho an\u00e1lises sobre o mercado de luxo em Florian\u00f3polis, lan\u00e7amentos de alto padr\u00e3o, tend\u00eancias de valoriza\u00e7\u00e3o e tudo o que um comprador exigente precisa saber antes de tomar uma decis\u00e3o patrimonial relevante. Tamb\u00e9m compartilho insights e novidades sobre o estilo de vida que cerca esse universo: mundo n\u00e1utico, gastronomia, eventos, esportes e tudo o que conecta Florian\u00f3polis ao mundo do alto padr\u00e3o.\",\"sameAs\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\"],\"gender\":\"feminino\",\"knowsAbout\":[\"Im\u00f3veis de Luxo e Alto Padr\u00e3o\"],\"knowsLanguage\":[\"Portug\u00eas\",\"Ingl\u00eas\",\"Espanhol\"],\"jobTitle\":\"Diretora de Relacionamento e Marketing\",\"worksFor\":\"Luxury Home Floripa\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CASACOR SP 2021","description":"CASACOR SP 2021: El t\u00e9rmino universo casa nunca tuvo tanto sentido. Debido a un largo per\u00edodo de aislamiento, el concepto de vivir bien...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/","og_locale":"es_ES","og_type":"article","og_title":"CASACOR SP 2021","og_description":"Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, Casas, Coberturas, Terrenos e Lan\u00e7amentos Imobili\u00e1rios.","og_url":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/","og_site_name":"Luxury Home Floripa","article_publisher":"https:\/\/www.facebook.com\/luxuryhomefloripa","article_published_time":"2021-10-28T13:24:41+00:00","article_modified_time":"2023-02-24T14:59:09+00:00","og_image":[{"width":918,"height":612,"url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/10\/23-Tufi-Mousse-Salvador-Cordaro.jpg","type":"image\/jpeg"}],"author":"Day Rocco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Day Rocco","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#article","isPartOf":{"@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/"},"author":{"name":"Day Rocco","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/person\/a60113ff81d1c0dd057e6ea02b4067b4"},"headline":"CASACOR SP 2021","datePublished":"2021-10-28T13:24:41+00:00","dateModified":"2023-02-24T14:59:09+00:00","mainEntityOfPage":{"@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/"},"wordCount":536,"commentCount":0,"publisher":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#organization"},"image":{"@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/10\/23-Tufi-Mousse-Salvador-Cordaro.jpg","articleSection":["Decor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/","url":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/","name":"CASACOR SP 2021","isPartOf":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#primaryimage"},"image":{"@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/10\/23-Tufi-Mousse-Salvador-Cordaro.jpg","datePublished":"2021-10-28T13:24:41+00:00","dateModified":"2023-02-24T14:59:09+00:00","description":"CASACOR SP 2021: El t\u00e9rmino universo casa nunca tuvo tanto sentido. Debido a un largo per\u00edodo de aislamiento, el concepto de vivir bien...","breadcrumb":{"@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#primaryimage","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/10\/23-Tufi-Mousse-Salvador-Cordaro.jpg","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2021\/10\/23-Tufi-Mousse-Salvador-Cordaro.jpg","width":918,"height":612,"caption":"CASACOR SP 2021"},{"@type":"BreadcrumbList","@id":"https:\/\/luxuryhomefloripa.com.br\/es\/casa-cor-sp-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/luxuryhomefloripa.com.br\/"},{"@type":"ListItem","position":2,"name":"CASACOR SP 2021"}]},{"@type":"WebSite","@id":"https:\/\/luxuryhomefloripa.com.br\/#website","url":"https:\/\/luxuryhomefloripa.com.br\/","name":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis","description":"Imobili\u00e1ria em Jurer\u00ea com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, casas, coberturas, terrenos e lan\u00e7amentos imobili\u00e1rios","publisher":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#organization"},"alternateName":"Luxury Home Floripa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxuryhomefloripa.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/luxuryhomefloripa.com.br\/#organization","name":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis","alternateName":"Luxury Home Floripa","url":"https:\/\/luxuryhomefloripa.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","width":1200,"height":675,"caption":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis"},"image":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","sameAs":["https:\/\/www.instagram.com\/luxuryhomefloripa\/","https:\/\/maps.app.goo.gl\/ymFbE67htB8wpMeU9","https:\/\/www.facebook.com\/luxuryhomefloripa","https:\/\/www.linkedin.com\/in\/luxuryhomefloripa\/","https:\/\/www.pinterest.com\/luxuryhomefloripa\/","https:\/\/www.youtube.com\/@LuxuryHomeFloripa","https:\/\/x.com\/luxuryhomefln"],"description":"Imobili\u00e1ria em Jurer\u00ea com im\u00f3veis \u00e0 venda na cidade de Florian\u00f3polis e em toda a regi\u00e3o da grande Florian\u00f3polis. Equipe especializada no mercado de Florian\u00f3polis com mais de 20 anos de experi\u00eancia.","email":"dayrocco@luxuryhomefloripa.com.br","telephone":"+5548996606799","legalName":"LUXURY HOME FLORIPA","foundingDate":"2021-01-23","vatID":"57.909.495\/0001-93","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"address":{"@type":"PostalAddress","streetAddress":"R. Prof. Heinz Braunsperger, 88 - Loja 3 - Jurer\u00ea Internacional","addressLocality":"Florian\u00f3polis","addressRegion":"Santa Catarina","postalCode":"88053-680","addressCountry":"BR"},"priceRange":"$$$","hasMap":"https:\/\/maps.app.goo.gl\/ymFbE67htB8wpMeU9","geo":{"@type":"GeoCoordinates","latitude":-27.4386881,"longitude":-48.4831842},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday","https:\/\/schema.org\/Saturday","https:\/\/schema.org\/Sunday"],"opens":"00:00","closes":"23:59"},"aggregateRating":{"@type":"AggregateRating","ratingValue":"5.0","reviewCount":"25","bestRating":"5","worstRating":"1"},"identifier":{"@type":"PropertyValue","name":"CRECI","value":"11161"},"areaServed":{"@type":"City","name":"Florian\u00f3polis"},"employee":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#agent-day-rocco"}},{"@type":"Person","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/person\/a60113ff81d1c0dd057e6ea02b4067b4","name":"d\u00eda roco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","caption":"Day Rocco"},"description":"Sou especialista em im\u00f3veis de luxo, alto padr\u00e3o e investimentos imobili\u00e1rios no Sul do Brasil. Reconhecida pelo atendimento premium e bil\u00edngue, acompanho cada cliente desde a primeira busca at\u00e9 a entrega das chaves, conectando compradores e investidores aos empreendimentos mais exclusivos da ilha, de Jurer\u00ea Internacional ao Campeche, passando por Cacup\u00e9, Jo\u00e3o Paulo e Praia Brava. Fundadora da Luxury Home Floripa, acumulo mais de R$ 320 milh\u00f5es em vendas ao longo de cinco anos de atua\u00e7\u00e3o no mercado imobili\u00e1rio de alta renda. Aqui compartilho an\u00e1lises sobre o mercado de luxo em Florian\u00f3polis, lan\u00e7amentos de alto padr\u00e3o, tend\u00eancias de valoriza\u00e7\u00e3o e tudo o que um comprador exigente precisa saber antes de tomar uma decis\u00e3o patrimonial relevante. Tamb\u00e9m compartilho insights e novidades sobre o estilo de vida que cerca esse universo: mundo n\u00e1utico, gastronomia, eventos, esportes e tudo o que conecta Florian\u00f3polis ao mundo do alto padr\u00e3o.","sameAs":["https:\/\/luxuryhomefloripa.com.br\/"],"gender":"feminino","knowsAbout":["Im\u00f3veis de Luxo e Alto Padr\u00e3o"],"knowsLanguage":["Portug\u00eas","Ingl\u00eas","Espanhol"],"jobTitle":"Diretora de Relacionamento e Marketing","worksFor":"Luxury Home Floripa"}]}},"_links":{"self":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/posts\/8033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/comments?post=8033"}],"version-history":[{"count":0,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/posts\/8033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/media\/39205"}],"wp:attachment":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/media?parent=8033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/categories?post=8033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/tags?post=8033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}