{"id":67724,"date":"2025-02-11T12:10:13","date_gmt":"2025-02-11T15:10:13","guid":{"rendered":"https:\/\/luxuryhomefloripa.com\/?p=66124"},"modified":"2025-07-29T09:54:07","modified_gmt":"2025-07-29T12:54:07","slug":"campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025","status":"publish","type":"post","link":"https:\/\/luxuryhomefloripa.com.br\/es\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/","title":{"rendered":"El campe\u00f3n Andr\u00e9 Gaidzinski en camino a la Porsche Cup Brasil 2025"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El piloto catarinense Andr\u00e9 Gaidzinski est\u00e1 listo para competir en la temporada 2025 de la Porsche Cup Brasil. Con m\u00e1s de 30 trofeos ganados desde su regreso a las pistas en 2018, aspira a m\u00e1s victorias. Y, por ello, aspira a un rendimiento a\u00fan m\u00e1s impresionante en el automovilismo. Adem\u00e1s, cuenta con el apoyo de importantes patrocinadores que est\u00e1n consolidando su trayectoria en la categor\u00eda Sport del campeonato Sprint Challenge.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quem-e-andre-gaidzinski\">\u00bfQui\u00e9n es Andr\u00e9 Gaidzinski?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Profesionalismo, enfoque y dedicaci\u00f3n caracterizan la carrera de Andr\u00e9 Gaidzinski, un piloto apasionado por el automovilismo desde su juventud. Su carrera comenz\u00f3 en el karting en 1989 y progres\u00f3 a categor\u00edas prestigiosas como la F\u00f3rmula Ford y la F\u00f3rmula Chevrolet. Tras un periodo alejado de la competici\u00f3n, regres\u00f3 a la pista en 2018 y r\u00e1pidamente destac\u00f3 en la Porsche Cup Brasil, acumulando podios y consolid\u00e1ndose como un referente en este deporte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gaidzinski cerr\u00f3 la \u00faltima temporada de la Porsche Cup Brasil con broche de oro, terminando quinto en el Endurance Challenge 2024, disputado en circuitos de Argentina, Brasil y Portugal. Para 2025, su objetivo es llegar a\u00fan m\u00e1s lejos y ganar t\u00edtulos importantes en la categor\u00eda.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2025\/02\/andre-gaidzinski.webp\"><img decoding=\"async\" src=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2025\/02\/andre-gaidzinski.webp\" alt=\"\" class=\"wp-image-66126\"\/><\/a><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-trajetoria-de-sucesso-e-os-desafios-para-2025\">La trayectoria exitosa y los retos para 2025<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La preparaci\u00f3n para la Porsche Cup Brasil 2025 incluye una intensa rutina de entrenamiento. Gaidzinski se dedica actualmente a sesiones avanzadas en simuladores de \u00faltima generaci\u00f3n, manteniendo una rigurosa preparaci\u00f3n f\u00edsica e invirtiendo en desarrollo mental para optimizar su rendimiento en la pista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El campeonato constar\u00e1 de seis etapas, incluyendo carreras internacionales en circuitos emblem\u00e1ticos como Estoril y Portim\u00e3o en Portugal, as\u00ed como competiciones en Velocitta e Interlagos en Brasil. El reto promete ser intenso, y Gaidzinski est\u00e1 decidido a ganar m\u00e1s trofeos y llevar a Santa Catarina al podio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&quot;Quiero traer m\u00e1s trofeos a Santa Catarina y que la bandera de nuestro estado suba al podio de la Porsche Cup Brasil. Para lograrlo, cuento con el apoyo de todos los catarinenses&quot;, afirma Gaidzinski.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2025\/02\/14-Andre-Gaidzinski-2022-Endurance-7-ET-GO-9.webp\"><img decoding=\"async\" src=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2025\/02\/14-Andre-Gaidzinski-2022-Endurance-7-ET-GO-9-1024x682.webp\" alt=\"\" class=\"wp-image-66133\"\/><\/a><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-suporte-dos-patrocinadores-e-a-busca-pela-excelencia\">El apoyo de los patrocinadores y la b\u00fasqueda de la excelencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00e9xito de un piloto va m\u00e1s all\u00e1 de la pista, y Andr\u00e9 Gaidzinski cuenta con el apoyo de importantes patrocinadores. Entre ellos se encuentran Teltec Solutions, el patrocinador principal, as\u00ed como Savel Capital Partners y Fanatic.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-teltec-solutions-e-a-parceria-de-alto-desempenho\">Teltec Solutions y la asociaci\u00f3n de alto rendimiento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La colaboraci\u00f3n entre Gaidzinski y Teltec Solutions refleja valores fundamentales como la innovaci\u00f3n, el alto rendimiento y la b\u00fasqueda de la excelencia. Seg\u00fan Cesar Schmitzhaus, Director de Innovaci\u00f3n y Tecnolog\u00eda de la empresa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Estamos muy emocionados de renovar nuestra colaboraci\u00f3n con Gaidzinski para la temporada 2025 de la Copa Porsche. Su trayectoria refleja los valores fundamentales de Teltec y confiamos en que esta ser\u00e1 otra temporada de grandes logros.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-savel-capital-partners-dedicacao-e-precisao-nas-pistas\">Savel Capital Partners: dedicaci\u00f3n y precisi\u00f3n en las pistas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Savel Capital Partners tambi\u00e9n reafirma su confianza en el talento del conductor catarinense. Seg\u00fan Jo\u00e3o Pedro Fonseca Costa, director general de la empresa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Estamos muy entusiasmados por continuar nuestra colaboraci\u00f3n con Andr\u00e9 Gaidzinski para la Porsche Cup Brasil 2025. En 2024, vivimos momentos memorables en la etapa de Resistencia, lo que reforz\u00f3 nuestra convicci\u00f3n en los valores que compartimos: dedicaci\u00f3n, precisi\u00f3n y b\u00fasqueda constante de la excelencia.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-os-bastidores-da-porsche-cup-o-que-torna-os-carros-unicos\">Entre bastidores de la Porsche Cup: \u00bfQu\u00e9 hace que los coches sean \u00fanicos?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los aspectos interesantes de la Copa Porsche es la preparaci\u00f3n de los coches. Mucha gente se pregunta si los modelos que se usan en las carreras son los mismos que los que se usan en la carretera. Andr\u00e9 Gaidzinski lo explica:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El motor es el mismo, pero los coches se modifican en la divisi\u00f3n de motores de Porsche en Alemania, donde reciben un kit de competici\u00f3n. Este incluye una jaula antivuelco, un sistema de frenos mejorado y telemetr\u00eda avanzada. Adem\u00e1s, existe una estandarizaci\u00f3n global para garantizar la igualdad de condiciones en la competici\u00f3n.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-uma-jornada-de-superacao-e-alto-desempenho\">Un viaje de superaci\u00f3n y alto rendimiento<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de sus 30 a\u00f1os de experiencia, Gaidzinski ha competido contra grandes figuras del automovilismo, como Rubens Barrichello, Tony Kanaan y Nelsinho Piquet. En otras palabras, su carrera est\u00e1 marcada por los desaf\u00edos y la b\u00fasqueda incesante de la perfecci\u00f3n. El propio piloto enfatiza su compromiso con el automovilismo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Vivo al m\u00e1ximo el automovilismo. Tengo un simulador en casa, voy al gimnasio, trabajo mi salud mental y me dedico por completo. En 2022, qued\u00e9 subcampe\u00f3n, a un segundo y seis d\u00e9cimas del t\u00edtulo. Mi objetivo ahora es ser campe\u00f3n.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-esperar-da-porsche-cup-brasil-2025\">\u00bfQu\u00e9 esperar de la Porsche Cup Brasil 2025?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La temporada 2025 de la Porsche Cup Brasil promete ser una de las m\u00e1s desafiantes hasta la fecha. Con un calendario repleto de circuitos ic\u00f3nicos, la competici\u00f3n exige t\u00e9cnica, preparaci\u00f3n y estrategia para alcanzar la cima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El debut ser\u00e1 en marzo, en el Aut\u00f3dromo Velocitta, en Mogi Gua\u00e7u (SP), y los aficionados pueden esperar grandes disputas y actuaciones emocionantes.<\/strong><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-mentalidade-de-um-campeao-o-que-move-andre-gaidzinski\">La mentalidad de un campe\u00f3n: \u00bfQu\u00e9 impulsa a Andr\u00e9 Gaidzinski?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el automovilismo, el talento y la t\u00e9cnica son esenciales, pero la mentalidad del piloto marca la diferencia entre un competidor com\u00fan y un verdadero campe\u00f3n. Andr\u00e9 Gaidzinski cree que la b\u00fasqueda de la excelencia va mucho m\u00e1s all\u00e1 de la pista y requiere un conjunto de factores que incluyen disciplina, preparaci\u00f3n mental y resiliencia ante los desaf\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El piloto catarinense mantiene una rutina de entrenamiento estructurada que combina ejercicios f\u00edsicos, sesiones en simuladores de \u00faltima generaci\u00f3n e incluso asesoramiento psicol\u00f3gico especializado. Seg\u00fan \u00e9l, el control emocional es tan importante como la habilidad al volante:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>En la pista, todo ocurre en fracciones de segundo. Se necesitan reflejos r\u00e1pidos, pero tambi\u00e9n una mente equilibrada para tomar las mejores decisiones. La concentraci\u00f3n y la resiliencia son esenciales para superar la adversidad y lograr los mejores resultados.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta mentalidad fue uno de los pilares de su ascenso en la Copa Porsche de Brasil. Cada etapa representa una nueva oportunidad de aprendizaje, crecimiento y mejora.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Entre motores y estrategia: \u00bfC\u00f3mo estudia Gaidzinski cada carrera?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una carrera no se gana solo con la velocidad, sino tambi\u00e9n con la estrategia. Adem\u00e1s del entrenamiento pr\u00e1ctico, Andr\u00e9 Gaidzinski dedica tiempo al estudio a fondo de cada pista, analizando las trayectorias ideales, los puntos de frenado y aceleraci\u00f3n, las variaciones meteorol\u00f3gicas y las estrategias de los competidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta preparaci\u00f3n incluye:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>An\u00e1lisis de telemetr\u00eda:<\/strong> Los datos del autom\u00f3vil se analizan en detalle para comprender d\u00f3nde se puede mejorar el rendimiento.<\/li>\n\n\n\n<li><strong>Estudio de v\u00eddeos y mapas de pistas:<\/strong> Mirar carreras pasadas ayuda a identificar patrones de adelantamiento y puntos cr\u00edticos.<\/li>\n\n\n\n<li><strong>Simulaciones virtuales:<\/strong> Utilizando tecnolog\u00eda de \u00faltima generaci\u00f3n, Gaidzinski recrea las condiciones de la pista para optimizar tu rendimiento incluso antes de llegar a la pista de carreras.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El automovilismo es un deporte de alta precisi\u00f3n, y cada detalle marca la diferencia. La capacidad de anticipar escenarios y tomar decisiones r\u00e1pidas puede determinar el resultado de una carrera.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e1s all\u00e1 de las pistas: el impacto de Gaidzinski en el automovilismo brasile\u00f1o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Andr\u00e9 Gaidzinski no solo es un piloto destacado en la pista, sino que tambi\u00e9n desempe\u00f1a un papel fundamental en el fortalecimiento del automovilismo brasile\u00f1o. Con una trayectoria consolidada, inspira a nuevos talentos y contribuye a elevar el perfil de la Copa Porsche Brasil, demostrando el gran potencial del pa\u00eds en este deporte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, su trayectoria refuerza la importancia de invertir en infraestructura deportiva, tecnolog\u00eda y desarrollo de pilotos. Su trayectoria sirve de ejemplo para los j\u00f3venes que sue\u00f1an con dedicarse al automovilismo y buscan orientaci\u00f3n sobre los retos y oportunidades de la profesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El automovilismo exige una dedicaci\u00f3n total, pero tambi\u00e9n ofrece momentos incre\u00edbles. Quiero que mi historia inspire a otros pilotos a perseverar y creer en su potencial.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este esp\u00edritu de determinaci\u00f3n y superaci\u00f3n, Andr\u00e9 Gaidzinski sigue acelerando, construyendo un legado y dejando su huella en el automovilismo nacional e internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s informaci\u00f3n en la web oficial:<br><a href=\"https:\/\/gaidzinski.com\/\">https:\/\/gaidzinski.com\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El piloto catarinense Andr\u00e9 Gaidzinski est\u00e1 listo para competir en la temporada 2025 de la Porsche Cup Brasil. Tras ganar m\u00e1s de 30 trofeos desde su regreso a las pistas en 2018, aspira a m\u00e1s victorias y a un rendimiento a\u00fan m\u00e1s impresionante en el automovilismo. <\/p>","protected":false},"author":10,"featured_media":69350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_daextam_enable_autolinks":"1","footnotes":""},"categories":[1],"tags":[],"class_list":["post-67724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025<\/title>\n<meta name=\"description\" content=\"Campe\u00e3o Andr\u00e9 Gaidzinski: O automobilismo exige dedica\u00e7\u00e3o total, mas tamb\u00e9m proporciona momentos incr\u00edveis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxuryhomefloripa.com.br\/es\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025\" \/>\n<meta property=\"og:description\" content=\"Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, Casas, Coberturas, Terrenos e Lan\u00e7amentos Imobili\u00e1rios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxuryhomefloripa.com.br\/es\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxury Home Floripa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/luxuryhomefloripa\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-11T15:10:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T12:54:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/02\/andre_gaidzinski_banner-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Day Rocco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Day Rocco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/\"},\"author\":{\"name\":\"Day Rocco\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/person\\\/a60113ff81d1c0dd057e6ea02b4067b4\"},\"headline\":\"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025\",\"datePublished\":\"2025-02-11T15:10:13+00:00\",\"dateModified\":\"2025-07-29T12:54:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/\"},\"wordCount\":1345,\"publisher\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/andre_gaidzinski_banner-1.webp\",\"articleSection\":[\"Artigos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/\",\"name\":\"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/andre_gaidzinski_banner-1.webp\",\"datePublished\":\"2025-02-11T15:10:13+00:00\",\"dateModified\":\"2025-07-29T12:54:07+00:00\",\"description\":\"Campe\u00e3o Andr\u00e9 Gaidzinski: O automobilismo exige dedica\u00e7\u00e3o total, mas tamb\u00e9m proporciona momentos incr\u00edveis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/andre_gaidzinski_banner-1.webp\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/andre_gaidzinski_banner-1.webp\",\"width\":1600,\"height\":1066,\"caption\":\"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#website\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\",\"name\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\",\"description\":\"Imobili\u00e1ria em Jurer\u00ea com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, casas, coberturas, terrenos e lan\u00e7amentos imobili\u00e1rios\",\"publisher\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\"},\"alternateName\":\"Luxury Home Floripa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\",\"name\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\",\"alternateName\":\"Luxury Home Floripa\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"width\":1200,\"height\":675,\"caption\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\"},\"image\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/maps.app.goo.gl\\\/ymFbE67htB8wpMeU9\",\"https:\\\/\\\/www.facebook.com\\\/luxuryhomefloripa\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LuxuryHomeFloripa\",\"https:\\\/\\\/x.com\\\/luxuryhomefln\"],\"description\":\"Imobili\u00e1ria em Jurer\u00ea com im\u00f3veis \u00e0 venda na cidade de Florian\u00f3polis e em toda a regi\u00e3o da grande Florian\u00f3polis. Equipe especializada no mercado de Florian\u00f3polis com mais de 20 anos de experi\u00eancia.\",\"email\":\"dayrocco@luxuryhomefloripa.com.br\",\"telephone\":\"+5548996606799\",\"legalName\":\"LUXURY HOME FLORIPA\",\"foundingDate\":\"2021-01-23\",\"vatID\":\"57.909.495\\\/0001-93\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"R. Prof. Heinz Braunsperger, 88 - Loja 3 - Jurer\u00ea Internacional\",\"addressLocality\":\"Florian\u00f3polis\",\"addressRegion\":\"Santa Catarina\",\"postalCode\":\"88053-680\",\"addressCountry\":\"BR\"},\"priceRange\":\"$$$\",\"hasMap\":\"https:\\\/\\\/maps.app.goo.gl\\\/ymFbE67htB8wpMeU9\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":-27.4386881,\"longitude\":-48.4831842},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\",\"https:\\\/\\\/schema.org\\\/Saturday\",\"https:\\\/\\\/schema.org\\\/Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5.0\",\"reviewCount\":\"25\",\"bestRating\":\"5\",\"worstRating\":\"1\"},\"identifier\":{\"@type\":\"PropertyValue\",\"name\":\"CRECI\",\"value\":\"11161\"},\"areaServed\":{\"@type\":\"City\",\"name\":\"Florian\u00f3polis\"},\"employee\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#agent-day-rocco\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/person\\\/a60113ff81d1c0dd057e6ea02b4067b4\",\"name\":\"Day Rocco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"caption\":\"Day Rocco\"},\"description\":\"Sou especialista em im\u00f3veis de luxo, alto padr\u00e3o e investimentos imobili\u00e1rios no Sul do Brasil. Reconhecida pelo atendimento premium e bil\u00edngue, acompanho cada cliente desde a primeira busca at\u00e9 a entrega das chaves, conectando compradores e investidores aos empreendimentos mais exclusivos da ilha, de Jurer\u00ea Internacional ao Campeche, passando por Cacup\u00e9, Jo\u00e3o Paulo e Praia Brava. Fundadora da Luxury Home Floripa, acumulo mais de R$ 320 milh\u00f5es em vendas ao longo de cinco anos de atua\u00e7\u00e3o no mercado imobili\u00e1rio de alta renda. Aqui compartilho an\u00e1lises sobre o mercado de luxo em Florian\u00f3polis, lan\u00e7amentos de alto padr\u00e3o, tend\u00eancias de valoriza\u00e7\u00e3o e tudo o que um comprador exigente precisa saber antes de tomar uma decis\u00e3o patrimonial relevante. Tamb\u00e9m compartilho insights e novidades sobre o estilo de vida que cerca esse universo: mundo n\u00e1utico, gastronomia, eventos, esportes e tudo o que conecta Florian\u00f3polis ao mundo do alto padr\u00e3o.\",\"sameAs\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\"],\"gender\":\"feminino\",\"knowsAbout\":[\"Im\u00f3veis de Luxo e Alto Padr\u00e3o\"],\"knowsLanguage\":[\"Portug\u00eas\",\"Ingl\u00eas\",\"Espanhol\"],\"jobTitle\":\"Diretora de Relacionamento e Marketing\",\"worksFor\":\"Luxury Home Floripa\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El campe\u00f3n Andr\u00e9 Gaidzinski en camino a la Porsche Cup Brasil 2025","description":"El campe\u00f3n Andr\u00e9 Gaidzinski: El deporte del motor exige una dedicaci\u00f3n total, pero tambi\u00e9n ofrece momentos incre\u00edbles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxuryhomefloripa.com.br\/es\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025","og_description":"Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, Casas, Coberturas, Terrenos e Lan\u00e7amentos Imobili\u00e1rios.","og_url":"https:\/\/luxuryhomefloripa.com.br\/es\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/","og_site_name":"Luxury Home Floripa","article_publisher":"https:\/\/www.facebook.com\/luxuryhomefloripa","article_published_time":"2025-02-11T15:10:13+00:00","article_modified_time":"2025-07-29T12:54:07+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/02\/andre_gaidzinski_banner-1.webp","type":"image\/webp"}],"author":"Day Rocco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Day Rocco","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/#article","isPartOf":{"@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/"},"author":{"name":"Day Rocco","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/person\/a60113ff81d1c0dd057e6ea02b4067b4"},"headline":"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025","datePublished":"2025-02-11T15:10:13+00:00","dateModified":"2025-07-29T12:54:07+00:00","mainEntityOfPage":{"@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/"},"wordCount":1345,"publisher":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#organization"},"image":{"@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/02\/andre_gaidzinski_banner-1.webp","articleSection":["Artigos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/","url":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/","name":"El campe\u00f3n Andr\u00e9 Gaidzinski en camino a la Porsche Cup Brasil 2025","isPartOf":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/#primaryimage"},"image":{"@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/02\/andre_gaidzinski_banner-1.webp","datePublished":"2025-02-11T15:10:13+00:00","dateModified":"2025-07-29T12:54:07+00:00","description":"El campe\u00f3n Andr\u00e9 Gaidzinski: El deporte del motor exige una dedicaci\u00f3n total, pero tambi\u00e9n ofrece momentos incre\u00edbles.","breadcrumb":{"@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/#primaryimage","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/02\/andre_gaidzinski_banner-1.webp","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/02\/andre_gaidzinski_banner-1.webp","width":1600,"height":1066,"caption":"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/luxuryhomefloripa.com.br\/campeao-andre-gaidzinski-e-sua-jornada-rumo-a-porsche-cup-brasil-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/luxuryhomefloripa.com.br\/"},{"@type":"ListItem","position":2,"name":"Campe\u00e3o Andr\u00e9 Gaidzinski rumo \u00e0 Porsche Cup Brasil 2025"}]},{"@type":"WebSite","@id":"https:\/\/luxuryhomefloripa.com.br\/#website","url":"https:\/\/luxuryhomefloripa.com.br\/","name":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis","description":"Imobili\u00e1ria em Jurer\u00ea com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, casas, coberturas, terrenos e lan\u00e7amentos imobili\u00e1rios","publisher":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#organization"},"alternateName":"Luxury Home Floripa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxuryhomefloripa.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/luxuryhomefloripa.com.br\/#organization","name":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis","alternateName":"Luxury Home Floripa","url":"https:\/\/luxuryhomefloripa.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","width":1200,"height":675,"caption":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis"},"image":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","sameAs":["https:\/\/www.instagram.com\/luxuryhomefloripa\/","https:\/\/maps.app.goo.gl\/ymFbE67htB8wpMeU9","https:\/\/www.facebook.com\/luxuryhomefloripa","https:\/\/www.linkedin.com\/in\/luxuryhomefloripa\/","https:\/\/www.pinterest.com\/luxuryhomefloripa\/","https:\/\/www.youtube.com\/@LuxuryHomeFloripa","https:\/\/x.com\/luxuryhomefln"],"description":"Imobili\u00e1ria em Jurer\u00ea com im\u00f3veis \u00e0 venda na cidade de Florian\u00f3polis e em toda a regi\u00e3o da grande Florian\u00f3polis. Equipe especializada no mercado de Florian\u00f3polis com mais de 20 anos de experi\u00eancia.","email":"dayrocco@luxuryhomefloripa.com.br","telephone":"+5548996606799","legalName":"LUXURY HOME FLORIPA","foundingDate":"2021-01-23","vatID":"57.909.495\/0001-93","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"address":{"@type":"PostalAddress","streetAddress":"R. Prof. Heinz Braunsperger, 88 - Loja 3 - Jurer\u00ea Internacional","addressLocality":"Florian\u00f3polis","addressRegion":"Santa Catarina","postalCode":"88053-680","addressCountry":"BR"},"priceRange":"$$$","hasMap":"https:\/\/maps.app.goo.gl\/ymFbE67htB8wpMeU9","geo":{"@type":"GeoCoordinates","latitude":-27.4386881,"longitude":-48.4831842},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday","https:\/\/schema.org\/Saturday","https:\/\/schema.org\/Sunday"],"opens":"00:00","closes":"23:59"},"aggregateRating":{"@type":"AggregateRating","ratingValue":"5.0","reviewCount":"25","bestRating":"5","worstRating":"1"},"identifier":{"@type":"PropertyValue","name":"CRECI","value":"11161"},"areaServed":{"@type":"City","name":"Florian\u00f3polis"},"employee":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#agent-day-rocco"}},{"@type":"Person","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/person\/a60113ff81d1c0dd057e6ea02b4067b4","name":"d\u00eda roco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","caption":"Day Rocco"},"description":"Sou especialista em im\u00f3veis de luxo, alto padr\u00e3o e investimentos imobili\u00e1rios no Sul do Brasil. Reconhecida pelo atendimento premium e bil\u00edngue, acompanho cada cliente desde a primeira busca at\u00e9 a entrega das chaves, conectando compradores e investidores aos empreendimentos mais exclusivos da ilha, de Jurer\u00ea Internacional ao Campeche, passando por Cacup\u00e9, Jo\u00e3o Paulo e Praia Brava. Fundadora da Luxury Home Floripa, acumulo mais de R$ 320 milh\u00f5es em vendas ao longo de cinco anos de atua\u00e7\u00e3o no mercado imobili\u00e1rio de alta renda. Aqui compartilho an\u00e1lises sobre o mercado de luxo em Florian\u00f3polis, lan\u00e7amentos de alto padr\u00e3o, tend\u00eancias de valoriza\u00e7\u00e3o e tudo o que um comprador exigente precisa saber antes de tomar uma decis\u00e3o patrimonial relevante. Tamb\u00e9m compartilho insights e novidades sobre o estilo de vida que cerca esse universo: mundo n\u00e1utico, gastronomia, eventos, esportes e tudo o que conecta Florian\u00f3polis ao mundo do alto padr\u00e3o.","sameAs":["https:\/\/luxuryhomefloripa.com.br\/"],"gender":"feminino","knowsAbout":["Im\u00f3veis de Luxo e Alto Padr\u00e3o"],"knowsLanguage":["Portug\u00eas","Ingl\u00eas","Espanhol"],"jobTitle":"Diretora de Relacionamento e Marketing","worksFor":"Luxury Home Floripa"}]}},"_links":{"self":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/posts\/67724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/comments?post=67724"}],"version-history":[{"count":0,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/posts\/67724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/media\/69350"}],"wp:attachment":[{"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/media?parent=67724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/categories?post=67724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/es\/wp-json\/wp\/v2\/tags?post=67724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}