{"id":4693,"date":"2020-10-21T01:42:07","date_gmt":"2020-10-21T04:42:07","guid":{"rendered":"https:\/\/luxuryhomefloripa.com\/?p=4693"},"modified":"2023-04-21T12:47:01","modified_gmt":"2023-04-21T15:47:01","slug":"floripa-e-o-mercado-imobiliario","status":"publish","type":"post","link":"https:\/\/luxuryhomefloripa.com.br\/de\/floripa-e-o-mercado-imobiliario\/","title":{"rendered":"Immobilienmarkt in Florian\u00f3polis \u2013 alles Wissenswerte."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" sizes=\"(max-width: 800px) 100vw, 800px\" src=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2020\/10\/1-3-300x225.png\" alt=\"\" class=\"wp-image-4697\" srcset=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/1-3-300x225.png 300w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/1-3-768x576.png 768w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/1-3.png 800w\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Viele Menschen fragen sich, warum der Immobilienmarkt im Allgemeinen inmitten der durch COVID verursachten Krise boomt.<\/span> <span style=\"font-weight: 400;\">Um das gesamte Szenario zu verstehen, m\u00fcssen wir es in folgende Abschnitte unterteilen:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<h5><span style=\"font-weight: 400;\">Wirtschaftliche Ver\u00e4nderungen nach der Pandemie;<\/span><\/h5>\n<\/li>\n\n\n\n<li>\n<h5><span style=\"font-weight: 400;\">Die sozialen Ver\u00e4nderungen (vielleicht die gr\u00f6\u00dften des Jahrhunderts), die wir erleben.<\/span><\/h5>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-na-economia\"><span style=\"font-weight: 400;\"><img decoding=\"async\" class=\"wp-image-4695 aligncenter\" src=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2020\/10\/5-3-300x225.png\" alt=\"\" width=\"399\" height=\"299\" srcset=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/5-3-300x225.png 300w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/5-3-768x576.png 768w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/5-3.png 800w\" sizes=\"(max-width: 399px) 100vw, 399px\" \/>In der Wirtschaftswissenschaft:<\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<h6><span style=\"font-weight: 400;\">Niedrige Zinss\u00e4tze (die niedrigsten der letzten 20 Jahre);<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Eine Vielzahl von Hypothekenkreditlinien;<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Bewegung hin zur Risikodiversifizierung;<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Und es sucht nach Verm\u00f6genswerten, deren Wert weniger stark von Kursschwankungen beeinflusst wird.<\/span><\/h6>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Niedrige Zinsen machen Kredite daher g\u00fcnstiger und Hypothekenfinanzierungen attraktiver. Wir befinden uns im Zeitalter der niedrigen Zinsen.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Je kleiner das Portfolio, desto geringer die Rentabilit\u00e4t von festverzinslichen Anlagen (den konservativsten). Es wird empfohlen, das Portfolio langfristig mit Anlagen in variabel verzinsliche und festverzinsliche Wertpapiere zu diversifizieren.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Dadurch erh\u00f6ht sich das Risiko.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Immobilien in der \u00f6stlichen Region von Florian\u00f3polis haben in den letzten zwei Jahren im Durchschnitt um 201.160.000 USD an Wert gewonnen. Dies ist eine reale Bewertungszahl aus unserem Portfolio.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Der Quadratmeterpreis f\u00fcr Mietwohnungen in Florian\u00f3polis geh\u00f6rt zu den h\u00f6chsten im Land und erreicht f\u00fcr Objekte in Meeresn\u00e4he bis zu 70,00 R$.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-na-vida-social\"><span style=\"font-weight: 400;\">Im sozialen Leben:<\/span><\/h3>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-a-quarentena-nos-mostrou-que-se-autoconhecer-e-estar-bem-mentalmente-nos-permite-enfrentar-melhor-os-desafios\"><span style=\"font-weight: 400;\">Die Quarant\u00e4ne hat uns gezeigt, dass Selbsterkenntnis und psychisches Wohlbefinden uns in die Lage versetzen, Herausforderungen besser zu bew\u00e4ltigen.&nbsp;<\/span><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-nunca-se-falou-tanto-sobre-meditar-praticar-yoga-e-estudar-sobre-alimentos-mais-organicos\"><span style=\"font-weight: 400;\">Noch nie zuvor wurde so viel \u00fcber Meditation, Yoga und den vermehrten Konsum von Bio-Lebensmitteln gesprochen.&nbsp;<\/span><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-o-autocuidado-integral-corpo-mente-alma-e-um-caminho-sem-volta-depois-de-um-ano-em-que-saude-foi-pauta-oficial\"><span style=\"font-weight: 400;\">Ganzheitliche Selbstf\u00fcrsorge \u2013 f\u00fcr K\u00f6rper, Geist und Seele \u2013 ist nach einem Jahr, in dem Gesundheit ein offizielles Gespr\u00e4chsthema war, ein Weg ohne Wiederkehr.<\/span><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-medicos-fizeram-lives-professores-aprenderam-a-usar-as-salas-online-cursos-gratuitos-foram-exaustivamente-oferecidos-e-percebemos-que-se-formou-uma-auto-suficiencia-coletiva\"><span style=\"font-weight: 400;\">\u00c4rzte hielten Live-Sitzungen ab, Lehrer lernten den Umgang mit Online-Klassenzimmern, kostenlose Kurse wurden in gro\u00dfem Umfang angeboten, und wir erkannten, dass sich eine kollektive Selbstversorgung herausgebildet hatte.<\/span><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-se-olhamos-para-dentro-de-nossas-casas-do-nosso-modo-de-viver-de-consumir-de-se-relacionar-com-a-nossa-familia\"><span style=\"font-weight: 400;\">Wenn wir in unsere H\u00e4user hineinblicken, auf unsere Lebensweise, unsere Konsumgewohnheiten und unsere Beziehungen zu unseren Familien.<\/span><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-tudo-comecou-a-ser-questionado\"><span style=\"font-weight: 400;\">Alles wurde in Frage gestellt:<\/span><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<h6><span style=\"font-weight: 400;\">Schenke ich meiner Lebensqualit\u00e4t und der meiner Familie gen\u00fcgend Aufmerksamkeit?<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Lebe ich im Einklang mit meinen Idealen und Lebenszielen?<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Stimmt mein Wertesystem mit der Zukunft \u00fcberein, von der ich immer getr\u00e4umt habe?<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Da ich tats\u00e4chlich arbeiten kann&nbsp;<\/span><span style=\"font-weight: 400;\">Kann ich online dort leben, wo ich immer getr\u00e4umt habe?<\/span><\/h6>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-a-mudanca-ja-pode-ser-sentida-no-novo-exodo-urbano\"><span style=\"font-weight: 400;\">Der Wandel ist bereits im neuen Exodus der St\u00e4dte sp\u00fcrbar:<\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Das Konzept der Stadt hat sich im Laufe der Geschichte zu einem Eckpfeiler der menschlichen Evolution entwickelt. Wann immer etwas passiert...<\/span><a href=\"https:\/\/noticias.r7.com\/internacional\"> <b>Transformation,<\/b><\/a> <span style=\"font-weight: 400;\">Am h\u00e4ufigsten tritt es in st\u00e4dtischen Gebieten auf.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Dieses Ph\u00e4nomen zeichnete sich bereits mit der technologischen Revolution ab und gewann w\u00e4hrend der Pandemie an Dynamik.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Die Landflucht ist jedoch gering; die Menschen verlassen die gro\u00dfen st\u00e4dtischen Zentren und suchen kleinere st\u00e4dtische Zentren auf.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Und ein kleineres urbanes Zentrum mit Strand w\u00e4re perfekt, nicht wahr? Ja.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Allerdings ist Floripa auf den Radar von Menschen aus ganz Brasilien und der ganzen Welt gelangt. S\u00e3o Paulo, Rio Grande do Sul, Rio de Janeiro, Bras\u00edlia, Belo Horizonte, Mato Grosso do Sul und Mato Grosso sind die Hauptstaaten, aus denen diese neuen Einwohner kommen.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Auch aus dem Ausland ist die Zuwanderung brasilianischer Staatsb\u00fcrger, die hier investieren m\u00f6chten, beeindruckend. Hinzu kommt, dass Europ\u00e4er, Amerikaner und Kanadier Wohnungen f\u00fcr l\u00e4ngere Zeitr\u00e4ume mieten.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Diejenigen, die ihre Koffer f\u00fcr den Umzug in andere L\u00e4nder gepackt hatten, packten sie wieder aus und zeigten auf Florian\u00f3polis. Aber wie sollen wir unsere Eltern zur\u00fccklassen?<\/span><span style=\"font-weight: 400;\">Was passiert nach einer solchen Pandemie? Nein. Sie sind die wichtigsten Menschen f\u00fcr uns.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"300\" height=\"225\" sizes=\"(max-width: 800px) 100vw, 800px\" src=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2020\/10\/4-3-300x225.png\" alt=\"Dist\u00e2ncias de Floripa\" class=\"wp-image-4698\" srcset=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/4-3-300x225.png 300w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/4-3-768x576.png 768w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/4-3.png 800w\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\"> In 50 Minuten sind wir in S\u00e3o Paulo, 1 Stunde und 30 Minuten von Rio de Janeiro entfernt, und befinden uns in einem der 300 beliebtesten Touristenziele der Welt.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn der Baumarkt der Stadt \u00fcberhitzt ist, werden Neubauprojekte und Immobilien im Allgemeinen mit einer Wertsteigerung von 151.016.000 seit Beginn der Pandemie (7 Monate) verkauft, w\u00e4hrend die Investoren darauf gesetzt hatten, dass die Werte um 301.016.000 sinken w\u00fcrden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Daher \u00fcbersteigt die Nachfrage nach H\u00e4usern und Grundst\u00fccken, insbesondere in Wohnanlagen mit Sicherheitsdienst, die Nachfrage nach Wohnungen. Angebote f\u00fcr Gartenwohnungen gewinnen zunehmend an Wert.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-se-olharmos-para-as-mudancas-de-necessidades-de-consumo-podemos-fazer-uma-conta-rapida\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4699\" src=\"https:\/\/luxuryhomefloripa.com\/wp-content\/uploads\/2020\/10\/2-3-300x225.png\" alt=\"Floripa e riquezas naturais\" width=\"434\" height=\"326\" srcset=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/2-3-300x225.png 300w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/2-3-768x576.png 768w, https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/2-3.png 800w\" sizes=\"(max-width: 434px) 100vw, 434px\" \/>Wenn wir uns die Ver\u00e4nderungen der Verbraucherbed\u00fcrfnisse ansehen, k\u00f6nnen wir eine schnelle Berechnung durchf\u00fchren:<\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<h6><span style=\"font-weight: 400;\">Wer in einer Gro\u00dfstadt lebt, wei\u00df, wie viel das Leben dort f\u00fcr eine Familie kostet. Vergleicht man das mit Florian\u00f3polis, einer Stadt mit hohen Lebenshaltungskosten, fallen die Kosten f\u00fcr Schulen dort mit bis zu 2.500 R$ deutlich niedriger aus. Diese Spanne umfasst das gesamte Spektrum von traditionellen bis hin zu modernen Schulen. Im Vergleich zu S\u00e3o Paulo ist Florian\u00f3polis um etwa 601.160 R$ g\u00fcnstiger.<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Die Stadt ist sicher. Kinder k\u00f6nnen beispielsweise in den \u00f6stlichen Stadtteilen der Insel frei Fahrrad fahren.<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Obwohl es sich nicht um eine gro\u00dfe Stadt handelt, bietet sie eine hervorragende Auswahl an Restaurants, Superm\u00e4rkten, Einkaufszentren und anderen Dienstleistungen.<\/span><\/h6>\n<\/li>\n\n\n\n<li>\n<h6><span style=\"font-weight: 400;\">Das Gesundheitsnetzwerk ist umfassend und beinhaltet ein Netz exzellenter Krankenh\u00e4user in der N\u00e4he.&nbsp;<\/span><\/h6>\n<\/li>\n<\/ul>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-quer-conhecer-outras-maravilhas-de-floripa-leia-esse-artigo-sobre-viver-em-floripa\">M\u00f6chten Sie weitere Sehensw\u00fcrdigkeiten von Florian\u00f3polis entdecken? Lesen Sie diesen Artikel dar\u00fcber. <a href=\"https:\/\/luxuryhomefloripa.com\/2020\/10\/03\/mudar-para-viver-mais-e-melhor\/\">Leben in Florida<\/a>.<\/h6>","protected":false},"excerpt":{"rendered":"<p>Muitas pessoas est\u00e3o se perguntando porque o mercado imobili\u00e1rio em geral est\u00e1 aquecido, em meio a toda crise causada pelo COVID. Para entender todo o cen\u00e1rio, temos que dividir entre: Na economia: Ent\u00e3o os n\u00edveis baixos nos juros tornam o custo de empr\u00e9stimo mais barato e o financiamento imobili\u00e1rio mais atrativo. \u00c9 a chamada da &#8230;<\/p>","protected":false},"author":10,"featured_media":4700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_daextam_enable_autolinks":"","footnotes":""},"categories":[246],"tags":[],"class_list":["post-4693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mercado imobili\u00e1rio em Floripa, saiba tudo<\/title>\n<meta name=\"description\" content=\"Muitas pessoas est\u00e3o se perguntando porque o mercado imobili\u00e1rio em Floripa est\u00e1 aquecido, em meio a toda crise causada pelo COVID.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxuryhomefloripa.com.br\/de\/floripa-e-o-mercado-imobiliario\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado imobili\u00e1rio em Floripa, saiba tudo\" \/>\n<meta property=\"og:description\" content=\"Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, Casas, Coberturas, Terrenos e Lan\u00e7amentos Imobili\u00e1rios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxuryhomefloripa.com.br\/de\/floripa-e-o-mercado-imobiliario\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxury Home Floripa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/luxuryhomefloripa\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T04:42:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-21T15:47:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/3-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Day Rocco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Day Rocco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/\"},\"author\":{\"name\":\"Day Rocco\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/person\\\/a60113ff81d1c0dd057e6ea02b4067b4\"},\"headline\":\"Mercado imobili\u00e1rio em Floripa, saiba tudo\",\"datePublished\":\"2020-10-21T04:42:07+00:00\",\"dateModified\":\"2023-04-21T15:47:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/\"},\"wordCount\":850,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/3-4.png\",\"articleSection\":[\"Economia\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/\",\"name\":\"Mercado imobili\u00e1rio em Floripa, saiba tudo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/3-4.png\",\"datePublished\":\"2020-10-21T04:42:07+00:00\",\"dateModified\":\"2023-04-21T15:47:01+00:00\",\"description\":\"Muitas pessoas est\u00e3o se perguntando porque o mercado imobili\u00e1rio em Floripa est\u00e1 aquecido, em meio a toda crise causada pelo COVID.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/3-4.png\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/3-4.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/en\\\/floripa-e-o-mercado-imobiliario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado imobili\u00e1rio em Floripa, saiba tudo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#website\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\",\"name\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\",\"description\":\"Imobili\u00e1ria em Jurer\u00ea com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, casas, coberturas, terrenos e lan\u00e7amentos imobili\u00e1rios\",\"publisher\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\"},\"alternateName\":\"Luxury Home Floripa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#organization\",\"name\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\",\"alternateName\":\"Luxury Home Floripa\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"width\":1200,\"height\":675,\"caption\":\"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis\"},\"image\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/luxury-home-floripa.png\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/maps.app.goo.gl\\\/ymFbE67htB8wpMeU9\",\"https:\\\/\\\/www.facebook.com\\\/luxuryhomefloripa\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/luxuryhomefloripa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LuxuryHomeFloripa\",\"https:\\\/\\\/x.com\\\/luxuryhomefln\"],\"description\":\"Imobili\u00e1ria em Jurer\u00ea com im\u00f3veis \u00e0 venda na cidade de Florian\u00f3polis e em toda a regi\u00e3o da grande Florian\u00f3polis. Equipe especializada no mercado de Florian\u00f3polis com mais de 20 anos de experi\u00eancia.\",\"email\":\"dayrocco@luxuryhomefloripa.com.br\",\"telephone\":\"+5548996606799\",\"legalName\":\"LUXURY HOME FLORIPA\",\"foundingDate\":\"2021-01-23\",\"vatID\":\"57.909.495\\\/0001-93\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"R. Prof. Heinz Braunsperger, 88 - Loja 3 - Jurer\u00ea Internacional\",\"addressLocality\":\"Florian\u00f3polis\",\"addressRegion\":\"Santa Catarina\",\"postalCode\":\"88053-680\",\"addressCountry\":\"BR\"},\"priceRange\":\"$$$\",\"hasMap\":\"https:\\\/\\\/maps.app.goo.gl\\\/ymFbE67htB8wpMeU9\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":-27.4386881,\"longitude\":-48.4831842},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\",\"https:\\\/\\\/schema.org\\\/Friday\",\"https:\\\/\\\/schema.org\\\/Saturday\",\"https:\\\/\\\/schema.org\\\/Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5.0\",\"reviewCount\":\"25\",\"bestRating\":\"5\",\"worstRating\":\"1\"},\"identifier\":{\"@type\":\"PropertyValue\",\"name\":\"CRECI\",\"value\":\"11161\"},\"areaServed\":{\"@type\":\"City\",\"name\":\"Florian\u00f3polis\"},\"employee\":{\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#agent-day-rocco\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/#\\\/schema\\\/person\\\/a60113ff81d1c0dd057e6ea02b4067b4\",\"name\":\"Day Rocco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"url\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"contentUrl\":\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426\",\"caption\":\"Day Rocco\"},\"description\":\"Sou especialista em im\u00f3veis de luxo, alto padr\u00e3o e investimentos imobili\u00e1rios no Sul do Brasil. Reconhecida pelo atendimento premium e bil\u00edngue, acompanho cada cliente desde a primeira busca at\u00e9 a entrega das chaves, conectando compradores e investidores aos empreendimentos mais exclusivos da ilha, de Jurer\u00ea Internacional ao Campeche, passando por Cacup\u00e9, Jo\u00e3o Paulo e Praia Brava. Fundadora da Luxury Home Floripa, acumulo mais de R$ 320 milh\u00f5es em vendas ao longo de cinco anos de atua\u00e7\u00e3o no mercado imobili\u00e1rio de alta renda. Aqui compartilho an\u00e1lises sobre o mercado de luxo em Florian\u00f3polis, lan\u00e7amentos de alto padr\u00e3o, tend\u00eancias de valoriza\u00e7\u00e3o e tudo o que um comprador exigente precisa saber antes de tomar uma decis\u00e3o patrimonial relevante. Tamb\u00e9m compartilho insights e novidades sobre o estilo de vida que cerca esse universo: mundo n\u00e1utico, gastronomia, eventos, esportes e tudo o que conecta Florian\u00f3polis ao mundo do alto padr\u00e3o.\",\"sameAs\":[\"https:\\\/\\\/luxuryhomefloripa.com.br\\\/\"],\"gender\":\"feminino\",\"knowsAbout\":[\"Im\u00f3veis de Luxo e Alto Padr\u00e3o\"],\"knowsLanguage\":[\"Portug\u00eas\",\"Ingl\u00eas\",\"Espanhol\"],\"jobTitle\":\"Diretora de Relacionamento e Marketing\",\"worksFor\":\"Luxury Home Floripa\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Immobilienmarkt in Florian\u00f3polis \u2013 alles Wissenswerte.","description":"Muitas pessoas est\u00e3o se perguntando porque o mercado imobili\u00e1rio em Floripa est\u00e1 aquecido, em meio a toda crise causada pelo COVID.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxuryhomefloripa.com.br\/de\/floripa-e-o-mercado-imobiliario\/","og_locale":"de_DE","og_type":"article","og_title":"Mercado imobili\u00e1rio em Floripa, saiba tudo","og_description":"Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, Casas, Coberturas, Terrenos e Lan\u00e7amentos Imobili\u00e1rios.","og_url":"https:\/\/luxuryhomefloripa.com.br\/de\/floripa-e-o-mercado-imobiliario\/","og_site_name":"Luxury Home Floripa","article_publisher":"https:\/\/www.facebook.com\/luxuryhomefloripa","article_published_time":"2020-10-21T04:42:07+00:00","article_modified_time":"2023-04-21T15:47:01+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/3-4.png","type":"image\/png"}],"author":"Day Rocco","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Day Rocco","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#article","isPartOf":{"@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/"},"author":{"name":"Day Rocco","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/person\/a60113ff81d1c0dd057e6ea02b4067b4"},"headline":"Mercado imobili\u00e1rio em Floripa, saiba tudo","datePublished":"2020-10-21T04:42:07+00:00","dateModified":"2023-04-21T15:47:01+00:00","mainEntityOfPage":{"@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/"},"wordCount":850,"commentCount":0,"publisher":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#organization"},"image":{"@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#primaryimage"},"thumbnailUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/3-4.png","articleSection":["Economia"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/","url":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/","name":"Immobilienmarkt in Florian\u00f3polis \u2013 alles Wissenswerte.","isPartOf":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#primaryimage"},"image":{"@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#primaryimage"},"thumbnailUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/3-4.png","datePublished":"2020-10-21T04:42:07+00:00","dateModified":"2023-04-21T15:47:01+00:00","description":"Muitas pessoas est\u00e3o se perguntando porque o mercado imobili\u00e1rio em Floripa est\u00e1 aquecido, em meio a toda crise causada pelo COVID.","breadcrumb":{"@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#primaryimage","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/3-4.png","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2020\/10\/3-4.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/luxuryhomefloripa.com.br\/en\/floripa-e-o-mercado-imobiliario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/luxuryhomefloripa.com.br\/"},{"@type":"ListItem","position":2,"name":"Mercado imobili\u00e1rio em Floripa, saiba tudo"}]},{"@type":"WebSite","@id":"https:\/\/luxuryhomefloripa.com.br\/#website","url":"https:\/\/luxuryhomefloripa.com.br\/","name":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis","description":"Imobili\u00e1ria em Jurer\u00ea com Im\u00f3veis \u00e0 venda em Florian\u00f3polis. Apartamentos, casas, coberturas, terrenos e lan\u00e7amentos imobili\u00e1rios","publisher":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#organization"},"alternateName":"Luxury Home Floripa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxuryhomefloripa.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/luxuryhomefloripa.com.br\/#organization","name":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis","alternateName":"Luxury Home Floripa","url":"https:\/\/luxuryhomefloripa.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","width":1200,"height":675,"caption":"Luxury Home Floripa - Imobili\u00e1ria com Im\u00f3veis \u00e0 venda em Florian\u00f3polis"},"image":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/uploads\/2025\/11\/luxury-home-floripa.png","sameAs":["https:\/\/www.instagram.com\/luxuryhomefloripa\/","https:\/\/maps.app.goo.gl\/ymFbE67htB8wpMeU9","https:\/\/www.facebook.com\/luxuryhomefloripa","https:\/\/www.linkedin.com\/in\/luxuryhomefloripa\/","https:\/\/www.pinterest.com\/luxuryhomefloripa\/","https:\/\/www.youtube.com\/@LuxuryHomeFloripa","https:\/\/x.com\/luxuryhomefln"],"description":"Imobili\u00e1ria em Jurer\u00ea com im\u00f3veis \u00e0 venda na cidade de Florian\u00f3polis e em toda a regi\u00e3o da grande Florian\u00f3polis. Equipe especializada no mercado de Florian\u00f3polis com mais de 20 anos de experi\u00eancia.","email":"dayrocco@luxuryhomefloripa.com.br","telephone":"+5548996606799","legalName":"LUXURY HOME FLORIPA","foundingDate":"2021-01-23","vatID":"57.909.495\/0001-93","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"address":{"@type":"PostalAddress","streetAddress":"R. Prof. Heinz Braunsperger, 88 - Loja 3 - Jurer\u00ea Internacional","addressLocality":"Florian\u00f3polis","addressRegion":"Santa Catarina","postalCode":"88053-680","addressCountry":"BR"},"priceRange":"$$$","hasMap":"https:\/\/maps.app.goo.gl\/ymFbE67htB8wpMeU9","geo":{"@type":"GeoCoordinates","latitude":-27.4386881,"longitude":-48.4831842},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday","https:\/\/schema.org\/Friday","https:\/\/schema.org\/Saturday","https:\/\/schema.org\/Sunday"],"opens":"00:00","closes":"23:59"},"aggregateRating":{"@type":"AggregateRating","ratingValue":"5.0","reviewCount":"25","bestRating":"5","worstRating":"1"},"identifier":{"@type":"PropertyValue","name":"CRECI","value":"11161"},"areaServed":{"@type":"City","name":"Florian\u00f3polis"},"employee":{"@id":"https:\/\/luxuryhomefloripa.com.br\/#agent-day-rocco"}},{"@type":"Person","@id":"https:\/\/luxuryhomefloripa.com.br\/#\/schema\/person\/a60113ff81d1c0dd057e6ea02b4067b4","name":"Day Rocco","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","url":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","contentUrl":"https:\/\/luxuryhomefloripa.com.br\/wp-content\/litespeed\/avatar\/ec12d140de6d82c9af0be44e054543fe.jpg?ver=1784080426","caption":"Day Rocco"},"description":"Sou especialista em im\u00f3veis de luxo, alto padr\u00e3o e investimentos imobili\u00e1rios no Sul do Brasil. Reconhecida pelo atendimento premium e bil\u00edngue, acompanho cada cliente desde a primeira busca at\u00e9 a entrega das chaves, conectando compradores e investidores aos empreendimentos mais exclusivos da ilha, de Jurer\u00ea Internacional ao Campeche, passando por Cacup\u00e9, Jo\u00e3o Paulo e Praia Brava. Fundadora da Luxury Home Floripa, acumulo mais de R$ 320 milh\u00f5es em vendas ao longo de cinco anos de atua\u00e7\u00e3o no mercado imobili\u00e1rio de alta renda. Aqui compartilho an\u00e1lises sobre o mercado de luxo em Florian\u00f3polis, lan\u00e7amentos de alto padr\u00e3o, tend\u00eancias de valoriza\u00e7\u00e3o e tudo o que um comprador exigente precisa saber antes de tomar uma decis\u00e3o patrimonial relevante. Tamb\u00e9m compartilho insights e novidades sobre o estilo de vida que cerca esse universo: mundo n\u00e1utico, gastronomia, eventos, esportes e tudo o que conecta Florian\u00f3polis ao mundo do alto padr\u00e3o.","sameAs":["https:\/\/luxuryhomefloripa.com.br\/"],"gender":"feminino","knowsAbout":["Im\u00f3veis de Luxo e Alto Padr\u00e3o"],"knowsLanguage":["Portug\u00eas","Ingl\u00eas","Espanhol"],"jobTitle":"Diretora de Relacionamento e Marketing","worksFor":"Luxury Home Floripa"}]}},"_links":{"self":[{"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/posts\/4693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/comments?post=4693"}],"version-history":[{"count":0,"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/posts\/4693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/media\/4700"}],"wp:attachment":[{"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/media?parent=4693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/categories?post=4693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/luxuryhomefloripa.com.br\/de\/wp-json\/wp\/v2\/tags?post=4693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}